{"id":9712,"date":"2025-08-03T12:47:28","date_gmt":"2025-08-03T16:47:28","guid":{"rendered":"https:\/\/reporteoficial.net\/?p=9712"},"modified":"2025-08-03T12:47:29","modified_gmt":"2025-08-03T16:47:29","slug":"alcaldia-del-dn-realiza-operativo-medico-social-en-ensanche-espaillat","status":"publish","type":"post","link":"https:\/\/reporteoficial.net\/index.php\/2025\/08\/03\/alcaldia-del-dn-realiza-operativo-medico-social-en-ensanche-espaillat\/","title":{"rendered":"Alcald\u00eda del DN realiza operativo m\u00e9dico social en Ensanche Espaillat"},"content":{"rendered":"\n<p>Alrededor de mil personas recibieron consultas, medicamentos y raciones alimenticias<\/p>\n\n\n\n<p>Santo Domingo, DN- Como fruto del programa La Alcald\u00eda Llega a Ti, el cabildo impact\u00f3 este s\u00e1bado con un gran operativo m\u00e9dico social en el Ensanche Espaillat.<\/p>\n\n\n\n<p>Bajo las directrices de Carolina Mej\u00eda, se llev\u00f3 a cabo en la calle Julio de Pe\u00f1a Valdez esquina calle interior G del referido sector, acogido por los comunitarios, quienes se dieron cita desde tempranas horas de la ma\u00f1ana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-4-1024x682.jpeg\" alt=\"\" class=\"wp-image-9714\" srcset=\"https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-4-1024x682.jpeg 1024w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-4-300x200.jpeg 300w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-4-200x133.jpeg 200w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-4-768x512.jpeg 768w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-4-1536x1024.jpeg 1536w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-4-480x320.jpeg 480w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Junior \u201cNuno\u201d Castillo, vicepresidente del Concejo de Regidores, expres\u00f3: \u201cEn nombre de nuestra alcaldesa Carolina Mej\u00eda, queremos destacar la fortaleza comunitaria y la inversi\u00f3n municipal que viene haciendo el cabildo en cada uno de los barrios del Distrito Nacional\u201d.<\/p>\n\n\n\n<p>Asimismo, apunt\u00f3 que m\u00e1s all\u00e1 de las intervenciones que hace diariamente la alcald\u00eda, el sector se va a mantener saneado en la medida en la que sus comunitarios se comprometan con la limpieza del mismo.<\/p>\n\n\n\n<p>Raudy Vargas, coordinador de Gabinete Social, estuvo en representaci\u00f3n de la alcaldesa y enfatiz\u00f3 c\u00f3mo est\u00e1n dando cumplimiento a las soluciones acordadas por la ejecutiva municipal con los comunitarios el pasado jueves durante el programa La Alcald\u00eda Llega a Ti.<\/p>\n\n\n\n<p>\u201cNos sentimos sumamente orgullosos y agradecidos de que ustedes nos den un recibimiento como este. La verdad es que hay que felicitar a la dirigencia, a las juntas de vecinos y a todos los que han colaborado para que esta actividad del d\u00eda de hoy se lleve a cabo de esta manera magistral\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"590\" src=\"https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-3-1-1024x590.jpeg\" alt=\"\" class=\"wp-image-9715\" srcset=\"https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-3-1-1024x590.jpeg 1024w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-3-1-300x173.jpeg 300w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-3-1-200x115.jpeg 200w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-3-1-768x443.jpeg 768w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-3-1-1536x885.jpeg 1536w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/08\/Unknown-3-1-480x277.jpeg 480w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Adem\u00e1s, indic\u00f3 que ya se han hecho intervenciones puntuales a trav\u00e9s de todas las direcciones como Tr\u00e1nsito y Movilidad Urbana, Gesti\u00f3n Ambiental, Aseo Urbano, Obras Comunitarias, entre otras.<\/p>\n\n\n\n<p>El coordinador del Despacho, Jensen Acosta, dijo que es un privilegio estar d\u00e1ndole continuidad a todo lo acordado el pasado jueves, para el bienestar de los residentes del populoso sector en el que vivi\u00f3.<\/p>\n\n\n\n<p><em>Gran impacto en la comunidad<\/em><\/p>\n\n\n\n<p>Durante el operativo, la Direcci\u00f3n de Servicio Social y Desarrollo ofreci\u00f3 220 consultas generales, 74 consultas de pediatr\u00eda y fueron colocadas 61 vacunas.<\/p>\n\n\n\n<p>Adem\u00e1s, fueron entregadas 43 canastillas para mujeres embarazadas y raciones de leche y avena.<\/p>\n\n\n\n<p>Gracias al apoyo de los Comedores Econ\u00f3micos del Estado, se proporcion\u00f3 un total de 709 comidas cocinadas para los moradores del sector.<\/p>\n\n\n\n<p>Rosa Santana, presidenta de la Junta de Vecinos Varias Luces, indic\u00f3 que el barrio est\u00e1 bendecido porque durante tres d\u00edas han tenido un despliegue de acciones puntuales por parte de la alcald\u00eda.<\/p>\n\n\n\n<p>Tambi\u00e9n estuvieron encabezando el operativo: Altagracia Suero, directora de Servicio Social y Desarrollo; Jensen Acosta; coordinador del Despacho de la Alcaldesa; M\u00e1ximo Romero, en representaci\u00f3n del Direcci\u00f3n de Desarrollo Comunitario; el doctor Pablo Johnson, encargado M\u00e9dico del cabildo; entre otros.<\/p>\n\n\n\n<p>El pasado jueves, Mej\u00eda, al reunirse con los comunitarios, juntas de vecinos y organizaciones sin fines de lucro del Ensanche Espaillat, les exhort\u00f3 a que asuman sus responsabilidades que de manera individual tiene cada ciudadano, porque \u201cvivir en orden y limpieza es el inicio de comenzar a sentirnos bien\u201d.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alrededor de mil personas recibieron consultas, medicamentos y raciones alimenticias Santo Domingo, DN- Como fruto del programa La Alcald\u00eda Llega a Ti, el cabildo impact\u00f3 este s\u00e1bado con un gran operativo m\u00e9dico social en el Ensanche Espaillat. Bajo las directrices de Carolina Mej\u00eda, se llev\u00f3 a cabo en la calle Julio de Pe\u00f1a Valdez esquina calle interior G del referido sector, acogido por los comunitarios, quienes se dieron cita desde tempranas horas de la ma\u00f1ana. Junior \u201cNuno\u201d Castillo, vicepresidente del Concejo de Regidores, expres\u00f3: \u201cEn nombre de nuestra alcaldesa Carolina Mej\u00eda, queremos destacar la fortaleza comunitaria y la inversi\u00f3n municipal que viene haciendo el cabildo en cada uno de los barrios del Distrito Nacional\u201d. Asimismo, apunt\u00f3 que m\u00e1s all\u00e1 de las intervenciones que hace diariamente la alcald\u00eda, el sector se va a mantener saneado en la medida en la que sus comunitarios se comprometan con la limpieza del mismo. Raudy Vargas, coordinador de Gabinete Social, estuvo en representaci\u00f3n de la alcaldesa y enfatiz\u00f3 c\u00f3mo est\u00e1n dando cumplimiento a las soluciones acordadas por la ejecutiva municipal con los comunitarios el pasado jueves durante el programa La Alcald\u00eda Llega a Ti. \u201cNos sentimos sumamente orgullosos y agradecidos de que ustedes nos den &hellip;<\/p>\n","protected":false},"author":1,"featured_media":9713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[595,342,100,664],"class_list":["post-9712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-alcalde","tag-alcaldia-2","tag-noticias","tag-santo-domingo"],"acf":[],"_links":{"self":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/9712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/comments?post=9712"}],"version-history":[{"count":1,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/9712\/revisions"}],"predecessor-version":[{"id":9716,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/9712\/revisions\/9716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media\/9713"}],"wp:attachment":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media?parent=9712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/categories?post=9712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/tags?post=9712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}