{"id":9709,"date":"2025-08-03T11:37:14","date_gmt":"2025-08-03T15:37:14","guid":{"rendered":"https:\/\/reporteoficial.net\/?p=9709"},"modified":"2025-08-03T11:37:15","modified_gmt":"2025-08-03T15:37:15","slug":"amelia-reyes-resulta-electa-presidenta-de-sodomedi-logrando-el-voto-preferencial-del-electorado","status":"publish","type":"post","link":"https:\/\/reporteoficial.net\/index.php\/2025\/08\/03\/amelia-reyes-resulta-electa-presidenta-de-sodomedi-logrando-el-voto-preferencial-del-electorado\/","title":{"rendered":"Amelia Reyes resulta electa presidenta de SODOMEDI logrando el voto preferencial del electorado"},"content":{"rendered":"\n<p>Santo Domingo, R.D. \u2013 La destacada comunicadora y profesional de las relaciones p\u00fablicas Amelia Reyes fue electa como nueva presidenta de la Sociedad Dominicana de Medios Digitales (SODOMEDI), al encabezar la plancha \u00fanica presentada en las elecciones celebradas recientemente por la entidad, obteniendo el respaldo de mas de la mitad de los miembros activos.<\/p>\n\n\n\n<p>El proceso electoral transcurri\u00f3 de manera organizada, transparente y con alta participaci\u00f3n de los miembros, quienes manifestaron su respaldo absoluto a la gesti\u00f3n que liderar\u00e1 Reyes, conocida por su amplia trayectoria en el sector comunicaci\u00f3n, relaciones institucionales y responsabilidad social.<\/p>\n\n\n\n<p>Reyes agradeci\u00f3 la confianza depositada en su liderazgo y expres\u00f3 su compromiso de fortalecer la institucionalidad, la formaci\u00f3n continua y la proyecci\u00f3n nacional e internacional de los miembros de SODOMEDI. \u201cVamos a trabajar por un gremio unido, actualizado y con voz firme en los espacios donde se toman decisiones que impactan los medios digitales\u201d, puntualiz\u00f3.<\/p>\n\n\n\n<p>Con la participaci\u00f3n de las seccionales de SODOMEDI en Nueva York, liderada por su secretario general Amado Khoury, la provincia La Altagracia, bajo el liderazgo de Fernando Placeres, secretario general; y San Juan de la Maguana, con Franklin Garc\u00eda Moquete como secretario general, el proceso reflej\u00f3 la integraci\u00f3n y compromiso nacional e internacional de la membres\u00eda.<\/p>\n\n\n\n<p>La plancha \u201cInnovaci\u00f3n y Compromiso \u00c9tico con la Comunicaci\u00f3n Digital\u201d est\u00e1 integrada por destacados profesionales del sector digital. Acompa\u00f1an a Amelia Reyes en la direcci\u00f3n ejecutiva: Rita P\u00e9rez, como vicepresidenta; H\u00e9ctor M\u00e9ndez, como secretario general; Sime\u00f3n Alc\u00e1ntara, como director de Organizaci\u00f3n; Cynthia Mart\u00ednez, como directora de Finanzas; Viryi Baldera, como directora de Relaciones P\u00fablicas; Omar Rivera, como director de Asuntos Internacionales; Fahd Jacobo, como director de Capacitaci\u00f3n; Madeline Pe\u00f1a, como directora de Recreaci\u00f3n y Cultura; Juan Miguel Fox, como director de Asistencia Social; y Mario Lara, en calidad de vocal.<\/p>\n\n\n\n<p>Mientras, la Comisi\u00f3n de \u00c9tica se encuentra presidida por Joaqu\u00edn Hiraldo, y la integran como miembros Mirola Matos y Wal Polanco, quienes tendr\u00e1n la responsabilidad de velar por la conducta \u00e9tica y el cumplimiento de los principios que rigen la instituci\u00f3n.<\/p>\n\n\n\n<p>Por su parte, la Comisi\u00f3n Revisora est\u00e1 encabezada por Sugey Reyes como presidenta, y tendr\u00e1 como miembros a Julissa Morel y Robinson Castro, quienes asumir\u00e1n el rol de fiscalizaci\u00f3n y supervisi\u00f3n administrativa del per\u00edodo.<\/p>\n\n\n\n<p>La propuesta liderada por Reyes busca modernizar la gesti\u00f3n institucional de SODOMEDI, promover la capacitaci\u00f3n continua de sus miembros y afianzar los valores \u00e9ticos que deben regir el ejercicio responsable de los medios digitales en la Rep\u00fablica Dominicana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, R.D. \u2013 La destacada comunicadora y profesional de las relaciones p\u00fablicas Amelia Reyes fue electa como nueva presidenta de la Sociedad Dominicana de Medios Digitales (SODOMEDI), al encabezar la plancha \u00fanica presentada en las elecciones celebradas recientemente por la entidad, obteniendo el respaldo de mas de la mitad de los miembros activos. El proceso electoral transcurri\u00f3 de manera organizada, transparente y con alta participaci\u00f3n de los miembros, quienes manifestaron su respaldo absoluto a la gesti\u00f3n que liderar\u00e1 Reyes, conocida por su amplia trayectoria en el sector comunicaci\u00f3n, relaciones institucionales y responsabilidad social. Reyes agradeci\u00f3 la confianza depositada en su liderazgo y expres\u00f3 su compromiso de fortalecer la institucionalidad, la formaci\u00f3n continua y la proyecci\u00f3n nacional e internacional de los miembros de SODOMEDI. \u201cVamos a trabajar por un gremio unido, actualizado y con voz firme en los espacios donde se toman decisiones que impactan los medios digitales\u201d, puntualiz\u00f3. Con la participaci\u00f3n de las seccionales de SODOMEDI en Nueva York, liderada por su secretario general Amado Khoury, la provincia La Altagracia, bajo el liderazgo de Fernando Placeres, secretario general; y San Juan de la Maguana, con Franklin Garc\u00eda Moquete como secretario general, el proceso reflej\u00f3 la integraci\u00f3n y compromiso nacional &hellip;<\/p>\n","protected":false},"author":1,"featured_media":9710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1190,167,455],"class_list":["post-9709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-amelia-reyes","tag-medios","tag-sodomedi"],"acf":[],"_links":{"self":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/9709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/comments?post=9709"}],"version-history":[{"count":1,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/9709\/revisions"}],"predecessor-version":[{"id":9711,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/9709\/revisions\/9711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media\/9710"}],"wp:attachment":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media?parent=9709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/categories?post=9709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/tags?post=9709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}