{"id":9096,"date":"2025-05-16T20:32:11","date_gmt":"2025-05-17T00:32:11","guid":{"rendered":"https:\/\/reporteoficial.net\/?p=9096"},"modified":"2025-05-16T20:32:12","modified_gmt":"2025-05-17T00:32:12","slug":"carolina-mejia-activa-el-comite-de-prevencion-ante-alerta-roja-por-vaguada","status":"publish","type":"post","link":"https:\/\/reporteoficial.net\/index.php\/2025\/05\/16\/carolina-mejia-activa-el-comite-de-prevencion-ante-alerta-roja-por-vaguada\/","title":{"rendered":"Carolina Mej\u00eda activa el Comit\u00e9 de Prevenci\u00f3n ante alerta roja por vaguada"},"content":{"rendered":"\n<p>Santo Domingo, DN &#8211; Carolina Mej\u00eda activ\u00f3 este viernes y mantiene en sesi\u00f3n permanente el Comit\u00e9 de Prevenci\u00f3n, Mitigaci\u00f3n y Respuesta ante Desastres del Distrito Nacional, debido a la presencia de una vaguada que afecta varios puntos del pa\u00eds, provocando la declaratoria de alerta roja para la capital.<\/p>\n\n\n\n<p>La medida tomada por la alcaldesa busca ofrecer una respuesta inmediata ante cualquier situaci\u00f3n que pueda surgir debido a las fuertes lluvias que han impactado al Distrito Nacional en las \u00faltimas horas y las que est\u00e1n pronosticadas.<\/p>\n\n\n\n<p>Mej\u00eda encabez\u00f3 la reuni\u00f3n del comit\u00e9 en el Cuartel General del Cuerpo de Bomberos del DN, donde explic\u00f3 que la misma ten\u00eda como objetivo planificar personalmente las acciones que de manera coordinada se est\u00e1n realizando con todas las instituciones.<\/p>\n\n\n\n<p>\u201cAqu\u00ed pasamos revista a lo que cada una de las instituciones que conforman este comit\u00e9 y de los departamentos de la alcald\u00eda, las responsabilidades que tenemos y las acciones que hemos estado llevando a cabo\u201d, puntualiz\u00f3.<\/p>\n\n\n\n<p>Las brigadas operativas del cabildo, que incluyen personal, equipos, camiones succionadores y otros veh\u00edculos, han estado limpiando los filtrantes, imbornales y contenes en varios puntos cr\u00edticos como Barrio Mejoramiento Social, Anacaona, avenida 27 de Febrero esquina Dr. Delgado, en las cercan\u00edas del Club Para\u00edso, en el Evaristo Morales y la avenida George Washington, entre otros.<\/p>\n\n\n\n<p>Adem\u00e1s, se han tomado medidas para que la recolecci\u00f3n de desechos sea m\u00e1s expedita. Asimismo, los bomberos han estado acudiendo al llamado de ciudadanos para cortar \u00e1rboles y ramas ca\u00eddas, as\u00ed como drenar inundaciones.<\/p>\n\n\n\n<p>En la reuni\u00f3n de activaci\u00f3n participaron representantes de los ministerios de Salud P\u00fablica, Medio Ambiente y Obras P\u00fablicas, tambi\u00e9n del Intrant, Defensa Civil, Indomet, Edeeste y la Polic\u00eda Municipal. Adem\u00e1s, directores y coordinadores de todas las direcciones del cabildo.<\/p>\n\n\n\n<p>El Centro de Operaciones de Emergencias (COE) coloc\u00f3 a 21 provincias bajo alerta por la combinaci\u00f3n de una vaguada con una masa de aire h\u00famedo, produciendo aguaceros de moderados a fuertes.<\/p>\n\n\n\n<p>La Alcald\u00eda del Distrito Nacional insta a los dominicanos a mantenerse atentos a las informaciones servidas en los canales oficiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, DN &#8211; Carolina Mej\u00eda activ\u00f3 este viernes y mantiene en sesi\u00f3n permanente el Comit\u00e9 de Prevenci\u00f3n, Mitigaci\u00f3n y Respuesta ante Desastres del Distrito Nacional, debido a la presencia de una vaguada que afecta varios puntos del pa\u00eds, provocando la declaratoria de alerta roja para la capital. La medida tomada por la alcaldesa busca ofrecer una respuesta inmediata ante cualquier situaci\u00f3n que pueda surgir debido a las fuertes lluvias que han impactado al Distrito Nacional en las \u00faltimas horas y las que est\u00e1n pronosticadas. Mej\u00eda encabez\u00f3 la reuni\u00f3n del comit\u00e9 en el Cuartel General del Cuerpo de Bomberos del DN, donde explic\u00f3 que la misma ten\u00eda como objetivo planificar personalmente las acciones que de manera coordinada se est\u00e1n realizando con todas las instituciones. \u201cAqu\u00ed pasamos revista a lo que cada una de las instituciones que conforman este comit\u00e9 y de los departamentos de la alcald\u00eda, las responsabilidades que tenemos y las acciones que hemos estado llevando a cabo\u201d, puntualiz\u00f3. Las brigadas operativas del cabildo, que incluyen personal, equipos, camiones succionadores y otros veh\u00edculos, han estado limpiando los filtrantes, imbornales y contenes en varios puntos cr\u00edticos como Barrio Mejoramiento Social, Anacaona, avenida 27 de Febrero esquina Dr. Delgado, en las &hellip;<\/p>\n","protected":false},"author":1,"featured_media":9097,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[691,342,1011,808,100],"class_list":["post-9096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-alcaldesa","tag-alcaldia-2","tag-coe","tag-dn","tag-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/9096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/comments?post=9096"}],"version-history":[{"count":1,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/9096\/revisions"}],"predecessor-version":[{"id":9098,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/9096\/revisions\/9098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media\/9097"}],"wp:attachment":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media?parent=9096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/categories?post=9096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/tags?post=9096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}