{"id":8993,"date":"2025-03-27T20:17:03","date_gmt":"2025-03-28T00:17:03","guid":{"rendered":"https:\/\/reporteoficial.net\/?p=8993"},"modified":"2025-03-27T20:18:12","modified_gmt":"2025-03-28T00:18:12","slug":"books-and-drinks-llega-a-los-cines-este-27-de-marzo","status":"publish","type":"post","link":"https:\/\/reporteoficial.net\/index.php\/2025\/03\/27\/books-and-drinks-llega-a-los-cines-este-27-de-marzo\/","title":{"rendered":"\u201cBooks and Drinks\u201d llega a los cines este 27 de marzo"},"content":{"rendered":"\n<p>La comedia rom\u00e1ntica es protagonizada por Jackson Rathbone, Clara Lago y Nashla Bogaert.<\/p>\n\n\n\n<p>Santo Domingo.-Tras una exitosa premiere en Santo Domingo, la esperada pel\u00edcula \u201cBooks &amp; Drinks\u201d llega a las salas de cine de Rep\u00fablica Dominicana este 27 de marzo. Dirigida por Geoffrey Cowper, quien realiz\u00f3 varios episodios de la reconocida serie \u201cBerl\u00edn\u201d, spinoff de \u201cLa Casa de Papel\u201d, esta comedia rom\u00e1ntica promete enamorar al p\u00fablico con su mezcla de humor, romance y el inconfundible encanto del Caribe.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/03\/Unknown-1-9-1024x683.jpeg\" alt=\"\" class=\"wp-image-8997\" srcset=\"https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/03\/Unknown-1-9-1024x683.jpeg 1024w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/03\/Unknown-1-9-300x200.jpeg 300w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/03\/Unknown-1-9-200x133.jpeg 200w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/03\/Unknown-1-9-768x512.jpeg 768w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/03\/Unknown-1-9-1536x1024.jpeg 1536w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/03\/Unknown-1-9-480x320.jpeg 480w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2025\/03\/Unknown-1-9.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u201cBooks &amp; Drinks\u201d narra la historia de David, un librero de Brooklyn que viaja a Rep\u00fablica Dominicana tras descubrir que su padre, a quien cre\u00eda muerto, le ha dejado una inesperada herencia: una espectacular mansi\u00f3n en el Caribe. Su intenci\u00f3n es venderla r\u00e1pidamente y salvar su librer\u00eda, pero pronto se ve inmerso en la calidez y la magia de la isla.<\/p>\n\n\n\n<p>Con \u00abBooks &amp; Drinks\u00bb quisimos crear una historia que conecte con las emociones del p\u00fablico. Es una pel\u00edcula que habla sobre las segundas oportunidades, el reencuentro con las ra\u00edces y el poder de abrirse a lo inesperado, expres\u00f3 Cowper, director del filme.<\/p>\n\n\n\n<p>La comedia cuenta con un elenco de proyecci\u00f3n internacional, encabezado por el actor estadounidense Jackson Rathbone, conocido por interpretar a Jasper Hale en la saga \u201cTwilight\u201d; la actriz espa\u00f1ola Clara Lago, reconocida por su papel en la exitosa comedia \u201cOcho apellidos vascos\u201d; y la actriz dominicana Nashla Bogaert.<\/p>\n\n\n\n<p>Adem\u00e1s, el filme incluye la participaci\u00f3n de reconocidas figuras del cine dominicano, como H\u00e9ctor An\u00edbal, Luis Jos\u00e9 Germ\u00e1n y Yasser Michel\u00e9n, quienes aportan autenticidad y carisma a esta historia.<\/p>\n\n\n\n<p>Detr\u00e1s de este proyecto est\u00e1n los productores dominicanos Andr\u00e9s Rodr\u00edguez y Pablo Lozano, de Veranera Films, junto con la productora estadounidense &#8211; brit\u00e1nica Carol Dudley.<\/p>\n\n\n\n<p>\u201cBooks &amp; Drinks\u201d, la cual ha tenido un destacado recorrido por festivales internacionales y fue nominada a Mejor Pel\u00edcula en el Long Island International Film Festival, ya est\u00e1 disponible en cines de todo el pa\u00eds. Esta comedia rom\u00e1ntica, distribuida por Caribbean Films Distribution, promete ser una de las favoritas del a\u00f1o.<\/p>\n\n\n\n<p>Ficha t\u00e9cnica \u201cBooks and Drinks\u201d<\/p>\n\n\n\n<p>G\u00e9nero: Comedia Rom\u00e1ntica<br>Duraci\u00f3n: 97 min<br>Director: Geoffrey Cowper<br>Productores: Carol Dudley, Pablo Lozano, Andr\u00e9s Rodr\u00edguez<br>Guion original: Josep Ciutat<br>Montaje: Antonella Bosiak<br>Director de fotograf\u00eda: Jos\u00e9 Rosete<br>Compositor musical: Andr\u00e9s Rodr\u00edguez<br>Dise\u00f1o de sonido: Alain Mu\u00f1iz<br>Idioma: Espa\u00f1ol \/ Ingl\u00e9s<br>Distribuci\u00f3n nacional \u2013 Caribbean Films Distribution<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comedia rom\u00e1ntica es protagonizada por Jackson Rathbone, Clara Lago y Nashla Bogaert. Santo Domingo.-Tras una exitosa premiere en Santo Domingo, la esperada pel\u00edcula \u201cBooks &amp; Drinks\u201d llega a las salas de cine de Rep\u00fablica Dominicana este 27 de marzo. Dirigida por Geoffrey Cowper, quien realiz\u00f3 varios episodios de la reconocida serie \u201cBerl\u00edn\u201d, spinoff de \u201cLa Casa de Papel\u201d, esta comedia rom\u00e1ntica promete enamorar al p\u00fablico con su mezcla de humor, romance y el inconfundible encanto del Caribe. \u201cBooks &amp; Drinks\u201d narra la historia de David, un librero de Brooklyn que viaja a Rep\u00fablica Dominicana tras descubrir que su padre, a quien cre\u00eda muerto, le ha dejado una inesperada herencia: una espectacular mansi\u00f3n en el Caribe. Su intenci\u00f3n es venderla r\u00e1pidamente y salvar su librer\u00eda, pero pronto se ve inmerso en la calidez y la magia de la isla. Con \u00abBooks &amp; Drinks\u00bb quisimos crear una historia que conecte con las emociones del p\u00fablico. Es una pel\u00edcula que habla sobre las segundas oportunidades, el reencuentro con las ra\u00edces y el poder de abrirse a lo inesperado, expres\u00f3 Cowper, director del filme. La comedia cuenta con un elenco de proyecci\u00f3n internacional, encabezado por el actor estadounidense Jackson Rathbone, conocido por interpretar &hellip;<\/p>\n","protected":false},"author":1,"featured_media":8996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[543],"tags":[112,126,101,100],"class_list":["post-8993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-arte","tag-cine","tag-farandula","tag-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/8993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/comments?post=8993"}],"version-history":[{"count":2,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/8993\/revisions"}],"predecessor-version":[{"id":8998,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/8993\/revisions\/8998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media\/8996"}],"wp:attachment":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media?parent=8993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/categories?post=8993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/tags?post=8993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}