{"id":6975,"date":"2024-11-04T09:12:10","date_gmt":"2024-11-04T13:12:10","guid":{"rendered":"https:\/\/reporteoficial.net\/?p=6975"},"modified":"2024-11-04T09:12:10","modified_gmt":"2024-11-04T13:12:10","slug":"exportadores-de-rd-fortalecen-competitividad-en-the-global-produce-and-floral-show-2024","status":"publish","type":"post","link":"https:\/\/reporteoficial.net\/index.php\/2024\/11\/04\/exportadores-de-rd-fortalecen-competitividad-en-the-global-produce-and-floral-show-2024\/","title":{"rendered":"Exportadores de RD fortalecen competitividad en The Global Produce and Floral Show 2024"},"content":{"rendered":"\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-1 wp-block-group-is-layout-flex\">\n<p>Atlanta, Estados Unidos. \u2013 Empresas del sector agr\u00edcola dominicano participaron en la Global Produce &amp; Floral Show, organizada por la International Fresh Produce Association (IFPA). Este destacado evento, que reuni\u00f3 a m\u00e1s de 20,000 asistentes y m\u00e1s de 1,000 expositores de toda la cadena de suministro, es uno de los m\u00e1s importantes de la industria de productos frescos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/reporteoficial.net\/wp-content\/uploads\/2024\/11\/Plano-1024x683.jpeg\" alt=\"\" class=\"wp-image-6977\" srcset=\"https:\/\/reporteoficial.net\/wp-content\/uploads\/2024\/11\/Plano-1024x683.jpeg 1024w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2024\/11\/Plano-300x200.jpeg 300w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2024\/11\/Plano-200x133.jpeg 200w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2024\/11\/Plano-768x512.jpeg 768w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2024\/11\/Plano-480x320.jpeg 480w, https:\/\/reporteoficial.net\/wp-content\/uploads\/2024\/11\/Plano.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<p>Biviana Riveiro, directora ejecutiva del Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana (ProDominicana), destac\u00f3 \u201cLe hemos dado la oportunidad a nuestros exportadores de aprovechar las ventajas competitivas que ofrece el mercado estadounidense, bas\u00e1ndose en el gran trabajo que ha realizado el gobierno dominicano de la mano del presidente Luis Abinader, para continuar posicionando productos de calidad en este importante destino\u201d.&nbsp;<\/p>\n\n\n\n<p>Asimismo, Riveiro subray\u00f3 la importancia de que las empresas del sector agr\u00edcola sigan participando en eventos internacionales a trav\u00e9s de ProDominicana para adquirir conocimientos t\u00e9cnicos que puedan ser aplicados en el pa\u00eds.<\/p>\n\n\n\n<p>La apertura del stand pa\u00eds estuvo a cargo de Francisco Pe\u00f1a, gerente de la Red Nacional del Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana (ProDominicana) y Raiza Rodr\u00edguez, ejecutiva de negocios internacionales, quienes estuvieron acompa\u00f1ados por miembros del Consulado Dominicano en Atlanta. Durante el evento, se presentaron m\u00faltiples oportunidades que se traducen en intenciones de negocios para el sector agr\u00edcola dominicano y las ocho empresas exportadoras participantes.<\/p>\n\n\n\n<p>Se destaca que, el objetivo de ProDominicana es continuar incrementando las exportaciones de productos agr\u00edcolas al mercado norteamericano. Gracias a la amplia variedad de productos cultivados y elaborados en el territorio dominicano, especialmente los aguacates, las exportaciones hacia Estados Unidos han crecido de manera exponencial en los \u00faltimos a\u00f1os, convirti\u00e9ndose en el principal socio comercial del pa\u00eds.<\/p>\n\n\n\n<p>La Rep\u00fablica Dominicana ha exportado desde el 2020 hasta septiembre 2024 un total de US$28,659.6 millones hacia Estados Unidos. Entre los principales productos agr\u00edcolas exportados desde el a\u00f1o 2020 hasta septiembre 2024 se encuentran; los aguacates US$196.5 millones, tomates US$88.1 millones, los aj\u00edes morr\u00f3n y cubanela US$74,9 millones, y los pepinos frescos US$46.4 millones.<\/p>\n\n\n\n<p>Las empresas dominicanas participantes en el evento se encuentran: SinClair Fresh, Natural Field, Ka Anapali, AMR Agro, SWG Dominicana, Agrio Fresh, Mamamia y Beony. Estas compa\u00f1\u00edas presentaron una amplia gama de productos, incluyendo; lim\u00f3n, aj\u00ed cubanela y morr\u00f3n, coco, aguacate, tomate, pepino, entre otros.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atlanta, Estados Unidos. \u2013 Empresas del sector agr\u00edcola dominicano participaron en la Global Produce &amp; Floral Show, organizada por la International Fresh Produce Association (IFPA). Este destacado evento, que reuni\u00f3 a m\u00e1s de 20,000 asistentes y m\u00e1s de 1,000 expositores de toda la cadena de suministro, es uno de los m\u00e1s importantes de la industria de productos frescos. Biviana Riveiro, directora ejecutiva del Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana (ProDominicana), destac\u00f3 \u201cLe hemos dado la oportunidad a nuestros exportadores de aprovechar las ventajas competitivas que ofrece el mercado estadounidense, bas\u00e1ndose en el gran trabajo que ha realizado el gobierno dominicano de la mano del presidente Luis Abinader, para continuar posicionando productos de calidad en este importante destino\u201d.&nbsp; Asimismo, Riveiro subray\u00f3 la importancia de que las empresas del sector agr\u00edcola sigan participando en eventos internacionales a trav\u00e9s de ProDominicana para adquirir conocimientos t\u00e9cnicos que puedan ser aplicados en el pa\u00eds. La apertura del stand pa\u00eds estuvo a cargo de Francisco Pe\u00f1a, gerente de la Red Nacional del Centro de Exportaci\u00f3n e Inversi\u00f3n de la Rep\u00fablica Dominicana (ProDominicana) y Raiza Rodr\u00edguez, ejecutiva de negocios internacionales, quienes estuvieron acompa\u00f1ados por miembros del Consulado Dominicano en Atlanta. Durante el evento, se &hellip;<\/p>\n","protected":false},"author":1,"featured_media":6976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[539],"tags":[397,100,538],"class_list":["post-6975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-economia","tag-noticias","tag-prodominicana"],"acf":[],"_links":{"self":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/6975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/comments?post=6975"}],"version-history":[{"count":1,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/6975\/revisions"}],"predecessor-version":[{"id":6978,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/6975\/revisions\/6978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media\/6976"}],"wp:attachment":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media?parent=6975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/categories?post=6975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/tags?post=6975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}