{"id":2901,"date":"2024-03-19T21:41:19","date_gmt":"2024-03-20T01:41:19","guid":{"rendered":"https:\/\/reporteoficial.net\/?p=2901"},"modified":"2024-03-19T21:41:19","modified_gmt":"2024-03-20T01:41:19","slug":"encuestadora-horizon-research-consolida-liderazgo-de-isha-cabrera-como-candidata-a-diputada-de-ultramar","status":"publish","type":"post","link":"https:\/\/reporteoficial.net\/index.php\/2024\/03\/19\/encuestadora-horizon-research-consolida-liderazgo-de-isha-cabrera-como-candidata-a-diputada-de-ultramar\/","title":{"rendered":"Encuestadora Horizon Research consolida liderazgo de Isha Cabrera como candidata a diputada de Ultramar"},"content":{"rendered":"\n<p>Miami, FL.- La candidata a diputada del partido Fuerza del Pueblo, por la Circunscripci\u00f3n no.2 de Ultramar, Isha Cabrera, ha consolidado una vez m\u00e1s su liderazgo con el apoyo de la di\u00e1spora dominicana, as\u00ed lo ha revelando la prestigiosa encuestadora Horizon Research, quien ha batisinado que, Cabrera se alzar\u00e1 como la representante de todos los dominicanos en el exterior.<\/p>\n\n\n\n<p>De acuerdo a los niveles de Preferencia electoral para diputados de la circunscripci\u00f3n 2 de Ultramar y los encuestados de 18 a 50 a\u00f1os o m\u00e1s, Cabrera encabeza la intenci\u00f3n de votos en Puerto Rico, Las Islas, Chile, Panam\u00e1, Orlando, San Mart\u00edn, Curazao y Venezuela.<\/p>\n\n\n\n<p>La tambi\u00e9n miembro de la Direcci\u00f3n Central de la FP, fue proclamada candidata oficial por el presidente de esa organizaci\u00f3n pol\u00edtica, el Dr. Leonel Fern\u00e1ndez, quien se encuentra haciendo una breve visita a militantes del partido verde residentes en Miami, Florida.<\/p>\n\n\n\n<p>\u00abIsha Cabrera, manifest\u00f3 sentirse agradecida con todos los dominicanos que han cre\u00eddo en su proyecto congresual, record\u00e1ndoles que trabajar\u00e1 no s\u00f3lo por los simpatizantes de la FP, sino tambi\u00e9n por todos los que lleven sangre quisqueyana\u00bb.<\/p>\n\n\n\n<p>\u00abIndependientemente de la diferencia de partidos, en particular yo, que represento a la Fuerza del Pueblo, tenemos que tener pendiente que todos somos dominicanos, vamos a legislar no simplemente viendolo como una representante de la circunscripci\u00f3n 2 que comprende pa\u00edses como Puerto Rico, Florida, Panam\u00e1, Argentina entre otros, sino que buscamos legislar para todos, d\u00edgase Nueva York, Canad\u00e1, Las Islas, aunando esfuerzos con los respresentantes de las dem\u00e1s circunscripciones y llevar soluciones a toda nuestra di\u00e1spora\u201d detall\u00f3 la miembro de la Direcci\u00f3n Central residente en la Florida.<\/p>\n\n\n\n<p>Entre los ejes de su legislatura est\u00e1 crear un bloque de diputados para velar por las necesidades de los dominicanos en el exterior, as\u00ed como la reinserci\u00f3n de los compatriotas deportados, donde se buscar\u00e1 con este proyecto, que los mismos una vez lleguen a la Rep\u00fablica Dominicana, sean personas viables y \u00fatiles, que no sean juzgados nuevamente, sino que, puedan generar ingresos y aportar al pa\u00eds.<\/p>\n\n\n\n<p>Isha Cabrera, trae una pol\u00edtica diferente, primero busca escuchar, llevando a cabo varios recorridos, haciendo un trabajo extenso para conocer las necesidades de cada personas emigrante del pa\u00eds, y as\u00ed proceder a crear proyectos de ley que apliquen a las necesidades del dominicano que reside lejos de sus familias en tierras extranjeras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miami, FL.- La candidata a diputada del partido Fuerza del Pueblo, por la Circunscripci\u00f3n no.2 de Ultramar, Isha Cabrera, ha consolidado una vez m\u00e1s su liderazgo con el apoyo de la di\u00e1spora dominicana, as\u00ed lo ha revelando la prestigiosa encuestadora Horizon Research, quien ha batisinado que, Cabrera se alzar\u00e1 como la representante de todos los dominicanos en el exterior. De acuerdo a los niveles de Preferencia electoral para diputados de la circunscripci\u00f3n 2 de Ultramar y los encuestados de 18 a 50 a\u00f1os o m\u00e1s, Cabrera encabeza la intenci\u00f3n de votos en Puerto Rico, Las Islas, Chile, Panam\u00e1, Orlando, San Mart\u00edn, Curazao y Venezuela. La tambi\u00e9n miembro de la Direcci\u00f3n Central de la FP, fue proclamada candidata oficial por el presidente de esa organizaci\u00f3n pol\u00edtica, el Dr. Leonel Fern\u00e1ndez, quien se encuentra haciendo una breve visita a militantes del partido verde residentes en Miami, Florida. \u00abIsha Cabrera, manifest\u00f3 sentirse agradecida con todos los dominicanos que han cre\u00eddo en su proyecto congresual, record\u00e1ndoles que trabajar\u00e1 no s\u00f3lo por los simpatizantes de la FP, sino tambi\u00e9n por todos los que lleven sangre quisqueyana\u00bb. \u00abIndependientemente de la diferencia de partidos, en particular yo, que represento a la Fuerza del Pueblo, tenemos que tener &hellip;<\/p>\n","protected":false},"author":1,"featured_media":2902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,140],"tags":[100,125,144],"class_list":["post-2901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-politica","tag-noticias","tag-politica","tag-politica-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/2901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/comments?post=2901"}],"version-history":[{"count":1,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/2901\/revisions"}],"predecessor-version":[{"id":2903,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/2901\/revisions\/2903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media\/2902"}],"wp:attachment":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media?parent=2901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/categories?post=2901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/tags?post=2901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}