{"id":2125,"date":"2024-02-02T09:19:51","date_gmt":"2024-02-02T13:19:51","guid":{"rendered":"https:\/\/reporteoficial.net\/?p=2125"},"modified":"2024-02-02T09:19:51","modified_gmt":"2024-02-02T13:19:51","slug":"taina-almodovar-es-galardonada-por-su-aporte-a-la-comunidad-dominicana-en-el-exterior-en-premio-nacional-de-la-juventud","status":"publish","type":"post","link":"https:\/\/reporteoficial.net\/index.php\/2024\/02\/02\/taina-almodovar-es-galardonada-por-su-aporte-a-la-comunidad-dominicana-en-el-exterior-en-premio-nacional-de-la-juventud\/","title":{"rendered":"Ta\u00edna Almod\u00f3var es galardonada por su aporte a la comunidad dominicana en el exterior en Premio Nacional de la Juventud"},"content":{"rendered":"\n<p>Escarlin Pozofebrero 1, 2024 <br>El rengl\u00f3n \u201cAporte a la Comunidad Dominicana en el Exterior\u201d, del Premio Nacional de la Juventud, tiene un nombre y apellido: Ta\u00edna Almod\u00f3var, quien en esta \u00faltima edici\u00f3n fue galardonada por su talento y accionar.<\/p>\n\n\n\n<p>Ta\u00edna la artista dominicana residente en Madrid, fue reconocida por su destacada labor en el \u00e1mbito de la literatura infantil y juvenil, llevando consigo el orgullo de representar a su pa\u00eds a trav\u00e9s del arte.<\/p>\n\n\n\n<p>Desde su residencia en la capital espa\u00f1ola, ha demostrado un compromiso con la difusi\u00f3n cultural, impartiendo talleres de arte y escritura, especialmente dise\u00f1ados para ni\u00f1os dominicanos residentes en el extranjero y con limitados recursos.<\/p>\n\n\n\n<p>Su enfoque incorpora el uso de materiales reciclados, no solo fomentando la creatividad, sino tambi\u00e9n promoviendo la conciencia ambiental entre los ni\u00f1os y adolescentes.<\/p>\n\n\n\n<p>Adem\u00e1s, Ta\u00edna Almod\u00f3var ha dejado su huella en eventos internacionales, representando a la Rep\u00fablica Dominicana en la Feria del Libro de Madrid. Su participaci\u00f3n se destac\u00f3 con la creaci\u00f3n de un mural que captur\u00f3 la riqueza cultural.<\/p>\n\n\n\n<p>Otro de los logros m\u00e1s destacados de Ta\u00edna es la creaci\u00f3n de \u00abLa Menina Caribe\u00f1a\u00bb, un proyecto art\u00edstico que se erige como la segunda representaci\u00f3n de una Menina dominicana en Madrid, Espa\u00f1a.<\/p>\n\n\n\n<p>Esta obra, pintada a mano de manera artesanal a lo largo de dos semanas, no solo celebra el talento de Ta\u00edna como ilustradora, sino que tambi\u00e9n busc\u00f3 promover el turismo y la belleza de la Rep\u00fablica Dominicana en el escenario internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escarlin Pozofebrero 1, 2024 El rengl\u00f3n \u201cAporte a la Comunidad Dominicana en el Exterior\u201d, del Premio Nacional de la Juventud, tiene un nombre y apellido: Ta\u00edna Almod\u00f3var, quien en esta \u00faltima edici\u00f3n fue galardonada por su talento y accionar. Ta\u00edna la artista dominicana residente en Madrid, fue reconocida por su destacada labor en el \u00e1mbito de la literatura infantil y juvenil, llevando consigo el orgullo de representar a su pa\u00eds a trav\u00e9s del arte. Desde su residencia en la capital espa\u00f1ola, ha demostrado un compromiso con la difusi\u00f3n cultural, impartiendo talleres de arte y escritura, especialmente dise\u00f1ados para ni\u00f1os dominicanos residentes en el extranjero y con limitados recursos. Su enfoque incorpora el uso de materiales reciclados, no solo fomentando la creatividad, sino tambi\u00e9n promoviendo la conciencia ambiental entre los ni\u00f1os y adolescentes. Adem\u00e1s, Ta\u00edna Almod\u00f3var ha dejado su huella en eventos internacionales, representando a la Rep\u00fablica Dominicana en la Feria del Libro de Madrid. Su participaci\u00f3n se destac\u00f3 con la creaci\u00f3n de un mural que captur\u00f3 la riqueza cultural. Otro de los logros m\u00e1s destacados de Ta\u00edna es la creaci\u00f3n de \u00abLa Menina Caribe\u00f1a\u00bb, un proyecto art\u00edstico que se erige como la segunda representaci\u00f3n de una Menina dominicana en Madrid, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":2126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139,1],"tags":[112,120,100,130],"class_list":["post-2125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-noticias","tag-arte","tag-educacion","tag-noticias","tag-premio"],"acf":[],"_links":{"self":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/2125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/comments?post=2125"}],"version-history":[{"count":1,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/2125\/revisions"}],"predecessor-version":[{"id":2127,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/2125\/revisions\/2127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media\/2126"}],"wp:attachment":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media?parent=2125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/categories?post=2125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/tags?post=2125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}