{"id":2122,"date":"2024-02-02T05:51:23","date_gmt":"2024-02-02T09:51:23","guid":{"rendered":"https:\/\/reporteoficial.net\/?p=2122"},"modified":"2024-02-02T05:51:23","modified_gmt":"2024-02-02T09:51:23","slug":"referencia-presenta-instituciones-beneficiadas-con-programa-agenda-por-la-vida-2024","status":"publish","type":"post","link":"https:\/\/reporteoficial.net\/index.php\/2024\/02\/02\/referencia-presenta-instituciones-beneficiadas-con-programa-agenda-por-la-vida-2024\/","title":{"rendered":"Referencia presenta instituciones beneficiadas con programa \u201cAgenda por la Vida 2024\u201d"},"content":{"rendered":"\n<p>Santo Domingo, RD.- Referencia Laboratorio Cl\u00ednico dio a conocer a las doce instituciones sin fines de lucro que ser\u00e1n beneficiadas este a\u00f1o con la d\u00e9cima sexta edici\u00f3n de su proyecto de responsabilidad social \u201cAgenda por la Vida\u201d, para contribuir con las labores meritorias que realizan a favor de diferentes comunidades del pa\u00eds.<\/p>\n\n\n\n<p>En un comunicado Referencia record\u00f3 la din\u00e1mica del programa, en la cual se asigna a cada mes a una de las causas seleccionadas para que reciban los aportes econ\u00f3micos de la empresa y de las contribuciones que realizan los pacientes en las alcanc\u00edas colocadas en los centros de servicios a nivel nacional.<\/p>\n\n\n\n<p>En esta edici\u00f3n, la agenda rinde tributo a cada uno de los momentos que hacen de la existencia del ser humano, un ser \u00fanico y especial, y destaca en cada uno de sus meses los logros y las acciones que ejecutan las doce entidades.<\/p>\n\n\n\n<p>En el comunicado se reiter\u00f3 el compromiso social de Referencia Laboratorio Cl\u00ednico con las instituciones ben\u00e9ficas que, con su trabajo contin\u00fao, contribuyen con el bienestar de miles de dominicanos que viven en condiciones especiales de salud o de marginalidad social.<\/p>\n\n\n\n<p><strong>Las 12 entidades beneficiadas en el 2024<\/strong><\/p>\n\n\n\n<p>Ser\u00e1n favorecidas la Fundaci\u00f3n Luz del Ma\u00f1ana, de Santo Domingo Este; Fundaci\u00f3n Amigos contra el C\u00e1ncer Infantil (FACCI), Amigos por el S\u00edndrome de Down, Fundaci\u00f3n Dominicana Pro-Ayuda a Pacientes Renales y Trasplantados, Fundaci\u00f3n St. Jude y Heart Care Dominicana, de Santo Domingo.<\/p>\n\n\n\n<p>Asimismo, la Fundaci\u00f3n Luz y Esperanza por el Autismo, de Santiago; Unidad de Neonatolog\u00eda del Hospital Dr. Luis Morillo King, de La Vega y la Fundaci\u00f3n Nuestros Peque\u00f1os Hermanos, de San Pedro de Macor\u00eds<\/p>\n\n\n\n<p>Tambi\u00e9n, la Asociaci\u00f3n de Ciegos del Cibao de la Rep\u00fablica Dominicana, de Santiago; Fundaci\u00f3n Oncol\u00f3gica del Este (Fode) y el Hogar de Ancianos Inspiraci\u00f3n Divina, de Ban\u00ed.<\/p>\n\n\n\n<p><strong>Sobre Referencia Laboratorio Cl\u00ednico<\/strong><\/p>\n\n\n\n<p>Fue establecido en 1983 y desde entonces ha estado al servicio de la salud y con un inquebrantable compromiso con la calidad.<\/p>\n\n\n\n<p>Cuenta con un estricto sistema de control de calidad en sus diferentes departamentos t\u00e9cnicos, avalado por un programa de evaluaci\u00f3n externa de calidad por el Colegio Americano de Pat\u00f3logos (CAP), as\u00ed como la Certificaci\u00f3n ISO 9001, 15189 y 17025 (seg\u00fan alcance), entre otras.<\/p>\n\n\n\n<p>Actualmente dispone de la m\u00e1s amplia red de sucursales, con m\u00e1s de 59 centros de servicios a nivel nacional y 14 dentro de la Red Punto M\u00e9dico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, RD.- Referencia Laboratorio Cl\u00ednico dio a conocer a las doce instituciones sin fines de lucro que ser\u00e1n beneficiadas este a\u00f1o con la d\u00e9cima sexta edici\u00f3n de su proyecto de responsabilidad social \u201cAgenda por la Vida\u201d, para contribuir con las labores meritorias que realizan a favor de diferentes comunidades del pa\u00eds. En un comunicado Referencia record\u00f3 la din\u00e1mica del programa, en la cual se asigna a cada mes a una de las causas seleccionadas para que reciban los aportes econ\u00f3micos de la empresa y de las contribuciones que realizan los pacientes en las alcanc\u00edas colocadas en los centros de servicios a nivel nacional. En esta edici\u00f3n, la agenda rinde tributo a cada uno de los momentos que hacen de la existencia del ser humano, un ser \u00fanico y especial, y destaca en cada uno de sus meses los logros y las acciones que ejecutan las doce entidades. En el comunicado se reiter\u00f3 el compromiso social de Referencia Laboratorio Cl\u00ednico con las instituciones ben\u00e9ficas que, con su trabajo contin\u00fao, contribuyen con el bienestar de miles de dominicanos que viven en condiciones especiales de salud o de marginalidad social. Las 12 entidades beneficiadas en el 2024 Ser\u00e1n favorecidas la Fundaci\u00f3n Luz &hellip;<\/p>\n","protected":false},"author":1,"featured_media":2123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[150],"class_list":["post-2122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-agenda"],"acf":[],"_links":{"self":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/2122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/comments?post=2122"}],"version-history":[{"count":1,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/2122\/revisions"}],"predecessor-version":[{"id":2124,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/2122\/revisions\/2124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media\/2123"}],"wp:attachment":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media?parent=2122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/categories?post=2122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/tags?post=2122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}