{"id":10358,"date":"2025-11-02T18:02:11","date_gmt":"2025-11-02T22:02:11","guid":{"rendered":"https:\/\/reporteoficial.net\/?p=10358"},"modified":"2025-11-02T18:02:12","modified_gmt":"2025-11-02T22:02:12","slug":"industria-de-cruceros-continua-en-auge-rd-recibe-diez-nuevas-embarcaciones-en-su-itinerario","status":"publish","type":"post","link":"https:\/\/reporteoficial.net\/index.php\/2025\/11\/02\/industria-de-cruceros-continua-en-auge-rd-recibe-diez-nuevas-embarcaciones-en-su-itinerario\/","title":{"rendered":"Industria de Cruceros contin\u00faa en auge: RD recibe diez nuevas embarcaciones en su itinerario"},"content":{"rendered":"\n<p>Puerto R\u00edo Haina, SDO.- La Autoridad Portuaria Dominicana (APORDOM), calific\u00f3 como trascendental la llegada de diez nuevos cruceros por primera vez a la Rep\u00fablica Dominicana, a trav\u00e9s de las distintas terminales portuarias.<\/p>\n\n\n\n<p>APORDOM inform\u00f3 que, dentro del itinerario de cruceros, los que vendr\u00e1n al pa\u00eds por primera vez son: Aida SOL, de la l\u00ednea A\u00edda; Cel Xcel, de Celebrity Cruiser; Brilliant Lady, de Virgin Voyager; Brilliant OTS, de MSC Cruises; Rhapsody, de Royal Caribbean; Carnival Legend, de Carnival Cruiser; Majestic Princess y Coral Princess, de Princess Cruises; NCL Getawey y NCL Joy, de Norwegian Cruises Line.<\/p>\n\n\n\n<p>De su lado, el director ejecutivo de la Autoridad Portuaria Dominicana, Jean Luis Rodr\u00edguez, resalt\u00f3 la gran importancia del arribo de nuevos barcos, ya que esto consolida la confianza que tienen las l\u00edneas de cruceros en nuestro pa\u00eds como destino ideal para la visita de los viajeros por nuestras diferentes zonas costeras.<\/p>\n\n\n\n<p>En el reporte de llegada de los cruceristas en el mes de noviembre la instituci\u00f3n portuaria detall\u00f3 que llegar\u00e1n 67 buques, segunda mayor cantidad este a\u00f1o, siendo Ta\u00edno Bay la de mayor recepci\u00f3n con 40, seguida por Amber Cove con 23 y Cabo Rojo con 4.<\/p>\n\n\n\n<p>La Autoridad Portuaria Dominicana, mediante notificaci\u00f3n, reiter\u00f3 que de acuerdo a lo establecido en cuanto al calendario de proyecci\u00f3n de llegada de cruceristas, las fechas seleccionadas pueden cambiar debido a las condiciones del clima y modificaciones en las rutas determinadas por las l\u00edneas de cruceros.<\/p>\n\n\n\n<p>-Caracter\u00edsticas espec\u00edficas de los barcos<\/p>\n\n\n\n<p>Aida SOL cuenta con 253.3 metros de eslora con capacidad de navegaci\u00f3n de 21.8 nudos.<br>Cel Xcel tiene capacidad para 3,260 pasajeros y 1,400 tripulantes.<br>Brilliant Lady: capacidad para 2,762 pasajeros y 1,150 tripulantes, con eslora de 278 metros.<br>Brilliant OTS: 2,152 pasajeros y capacidad de navegaci\u00f3n de 25 nudos.<br>Majestic Princess: 330 metros de eslora, capacidad para 3,560 pasajeros y 1,346 tripulantes.<br>Coral Princess: capacidad para 2,000 pasajeros con 294 metros de eslora y velocidad de navegaci\u00f3n de 21.5 nudos.<br>Rhapsody: navegaci\u00f3n de 23 nudos, con 279 metros de eslora y capacidad para 2,040 pasajeros.<br>NCL Getawey: capacidad para 3,963 pasajeros, con 326 metros de eslora y 22.5 nudos de velocidad de navegaci\u00f3n.<br>Carnival Legend: capacidad de 2,124 pasajeros, 930 tripulantes, 293 metros de eslora y velocidad de navegaci\u00f3n de 22 nudos.<br>NCL Joy: cuenta con 333 metros de eslora, con capacidad para 3,776 pasajeros y 1,821 tripulantes.<\/p>\n\n\n\n<p>Direcci\u00f3n de Comunicaciones.<br>1 de noviembre de 2025.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puerto R\u00edo Haina, SDO.- La Autoridad Portuaria Dominicana (APORDOM), calific\u00f3 como trascendental la llegada de diez nuevos cruceros por primera vez a la Rep\u00fablica Dominicana, a trav\u00e9s de las distintas terminales portuarias. APORDOM inform\u00f3 que, dentro del itinerario de cruceros, los que vendr\u00e1n al pa\u00eds por primera vez son: Aida SOL, de la l\u00ednea A\u00edda; Cel Xcel, de Celebrity Cruiser; Brilliant Lady, de Virgin Voyager; Brilliant OTS, de MSC Cruises; Rhapsody, de Royal Caribbean; Carnival Legend, de Carnival Cruiser; Majestic Princess y Coral Princess, de Princess Cruises; NCL Getawey y NCL Joy, de Norwegian Cruises Line. De su lado, el director ejecutivo de la Autoridad Portuaria Dominicana, Jean Luis Rodr\u00edguez, resalt\u00f3 la gran importancia del arribo de nuevos barcos, ya que esto consolida la confianza que tienen las l\u00edneas de cruceros en nuestro pa\u00eds como destino ideal para la visita de los viajeros por nuestras diferentes zonas costeras. En el reporte de llegada de los cruceristas en el mes de noviembre la instituci\u00f3n portuaria detall\u00f3 que llegar\u00e1n 67 buques, segunda mayor cantidad este a\u00f1o, siendo Ta\u00edno Bay la de mayor recepci\u00f3n con 40, seguida por Amber Cove con 23 y Cabo Rojo con 4. La Autoridad Portuaria Dominicana, mediante notificaci\u00f3n, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":10359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[260],"tags":[1237,1360,100,630,124],"class_list":["post-10358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo","tag-cruceros","tag-embarcaciones","tag-noticias","tag-rd","tag-turismo"],"acf":[],"_links":{"self":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/10358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/comments?post=10358"}],"version-history":[{"count":1,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/10358\/revisions"}],"predecessor-version":[{"id":10360,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/posts\/10358\/revisions\/10360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media\/10359"}],"wp:attachment":[{"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/media?parent=10358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/categories?post=10358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporteoficial.net\/index.php\/wp-json\/wp\/v2\/tags?post=10358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}